{"id":530,"date":"2012-10-13T08:26:12","date_gmt":"2012-10-13T06:26:12","guid":{"rendered":"http:\/\/no194.org\/?p=530"},"modified":"2014-05-08T09:28:48","modified_gmt":"2014-05-08T07:28:48","slug":"nuovo-referendum-abrogativo-della-l-194-in-materia-di-aborto-il-testo-dei-quesiti-referendari","status":"publish","type":"post","link":"https:\/\/www.no194.it\/wordpress\/archives\/530","title":{"rendered":"NUOVO REFERENDUM ABROGATIVO DELLA L. 194 IN MATERIA DI ABORTO : IL TESTO DEI QUESITI REFERENDARI"},"content":{"rendered":"<p>Dopo aver trattato in passato la questione dei quesiti referendari , con tutte le sue implicazioni , anche pretestuose e strumentali , passiamo ora all\u2019analisi del loro testo , che viene per la prima volta qui reso pubblico .<\/p>\n<p>Una premessa doverosa .<\/p>\n<p>Il manifesto della nostra iniziativa referendaria , da me redatto e riportato sul sito <a href=\"http:\/\/www.no194.org\/\">www.no194.org<\/a> , quello ufficiale dell\u2019associazione no194 e dell\u2019omonimo comitato no194 , che vanta oltre 11 000 aderenti , sigla che rappresenta la prima organizzazione antiabortista italiana , recita :<\/p>\n<p><em>\u201c Piuttosto , alla luce del pericolo di una ( peraltro infondata ) censura da parte della Consulta , i quesiti referendari avranno essenzialmente come oggetto le norme pi\u00f9 significative della legge , che si aggiungeranno cos\u00ec al quesito sull\u2019abrogazione totale della legge .<\/em><\/p>\n<p><em>Tra le disposizioni pi\u00f9 controverse ed impopolari della 194 , in particolare ed anzitutto , debbono annoverarsi l\u2019art. 4 ( che riconosce il diritto di interruzione volontaria della gravidanza anche per mere ragioni economiche , morali e sociali nei primi 90 giorni ) e l\u2019art. 5 ( che attribuisce alla donna, anche se coniugata, il diritto di assumere la decisione abortiva senza coinvolgere il potenziale padre , che pu\u00f2 cos\u00ec legalmente rimanere del tutto ignaro dell\u2019evento ) . <\/em><\/p>\n<p><em>L\u2019iniziativa \u00e8 solo finalizzata all\u2019abrogazione della legge ( dall\u2019entrata in vigore della quale si sono registrati oltre 5 milioni di aborti , secondo i dati ufficiali del Ministero della Salute ) e rigetta ogni ipotesi di trattativa , che sarebbe inconcepibilmente effettuata sulla pelle del nostro prossimo .<\/em><\/p>\n<p><em>Di conseguenza , possibili effetti legislativi dell\u2019operazione in oggetto restrittivi sulla portata della 194 ( ed intermedi rispetto all\u2019obiettivo indicato ) , sarebbero frutto di una ( tra l\u2019altro ad oggi del tutto improbabile ) azione parlamentare totalmente unilaterale e non concordata con i promotori del referendum \u201c .<\/em><\/p>\n<p>Dal primo periodo , si prospetta in modo assolutamente pacifico :<\/p>\n<p>a ) la proposizione di un quesito sull\u2019abrogazione totale della legge ;<\/p>\n<p>b ) che , alla luce del pericolo di una ( peraltro infondata nel merito ) censura da parte del Consulta , i quesiti referendari avranno essenzialmente come oggetto le norme pi\u00f9 significative della legge , fermo restando il quesito abrogativo totale ( cosiddetto massimale ) .<\/p>\n<p>In particolar modo gli interventi della Corte Costituzionale potrebbero aver come oggetto due questioni :<\/p>\n<p>A ) il vuoto normativo conseguente all\u2019abrogazione totale della legge , anche alla luce della possibile non reviviscenza della disciplina prevista dal codice penale ed abrogata con la 194 ;<\/p>\n<p>B ) il contrasto con l\u2019art. 32 della carta , sotto il profilo della tutela del diritto alla salute della donna potenziale madre .<\/p>\n<p>In relazione a ciascuna di tali obiezioni , ho proceduto alla stesura di due quesiti , uno massimale e uno minimale , che , salve le rettifiche formali del caso ed ogni approfondita , opportuna ulteriore riflessione, dovrebbero essere definitivi e che , nel loro complesso , rappresentano l\u2019azione concretamente ( e sottolineo l\u2019avverbio , avulso dall\u2019approccio operativo dei sognatori )\u00a0 pi\u00f9 radicale e netta che pu\u00f2 essere esperita contro la legge 194 .<\/p>\n<p>1 ) Come ho pi\u00f9 volte precisato , il quesito massimale pu\u00f2 essere proposto anche formalmente in modo massimale o in modo formalmente non massimale , ma massimale nella sostanza .<\/p>\n<p>Il testo da me redatto viene qui convertito per fini divulgativi in una forma che consenta una diretta lettura delle disposizioni di legge che rimarrebbero vigenti , nei seguenti termini : <em>Volete che sia abrogata la legge 22 maggio 1978 n. 194 recante &#8220;Norme per la tutela sociale della maternit\u00e0 e sulla interruzione volontaria della gravidanza&#8221; , con riferimento agli artt. 1 , 2 , 3 , 4, , 5, 7 , 8 , 9 , 10 , 11 , 12 , 13, 14 , 15 , 16 , 20 , 21 , 22 ad eccezione quindi dell\u2019art. 6 , con solo riferimento alle parole \u201c L\u2019interruzione volontaria della gravidanza \u201c , \u201c pu\u00f2 essere praticata \u201c , \u201c quando la gravidanza o il parto comportino un grave pericolo per la vita della donna \u201c , degli interi artt. 17 e 18 , che stabiliscono le pene per chiunque cagiona l\u2019interruzione di gravidanza senza il consenso della donna , e dell\u2019art. 19 , con riferimento alle parole \u201cChiunque cagiona l&#8217;interruzione volontaria della gravidanza \u201c , \u201c\u00e8 punito con la reclusione sino a tre anni \u201c di cui al primo comma , alle parole \u201c La donna \u00e8 punita \u201c di cui al quarto comma , alle parole \u201cQuando l&#8217;interruzione volontaria della gravidanza avviene su donna minore degli anni diciotto, o interdetta , \u201c, \u201c chi la cagiona \u00e8 punito con \u201c , \u201c pene \u201c , \u201c aumentate fino alla met\u00e0 \u201c di cui al quinto comma e alle parole \u201cSe dai fatti previsti dai commi precedenti deriva la morte della donna, si applica la reclusione da tre a sette anni \u201c di cui al sesto comma ? <\/em><\/p>\n<p>Ecco che l\u2019abrogazione , tra l\u2019altro , oltre che degli artt. 4 e 5 ( che hanno introdotto il libero aborto nei primi 90 giorni di gravidanza ) , dell\u2019art. 6 limitatamente alla lett. b ( che riguarda i casi di interruzione della gravidanza anche dopo i primi tre mesi di gestazione , ammessa qualora siano accertati processi patologici tali da determinare un grave pericolo per la salute fisica o psichica della donna ) , lascerebbe sopravvivere il 6 lett. a , con il quale si ammette l\u2019aborto anche dopo ( ma , ovviamente , gi\u00e0 prima ) il 90\u00b0 giorno di gravidanza nel caso di grave pericolo per la vita della donna , per effetto della gestazione o del parto .<\/p>\n<p>Come pi\u00f9 volte ribadito , tale ultima ipotesi sostanziale non \u00e8 stata introdotta della 194 , perch\u00e9 anche anteriormente alla sua entrata in vigore , anno 1978 , quella fattispecie rientrava nella generale causa di giustificazione di cui all\u2019art. 54 c.p. , non essendo , in particolare , punibile quella condotta per stato di necessit\u00e0 ( della madre ) , quindi per la necessit\u00e0 di salvare s\u00e9 o altri dal pericolo attuale di danno grave alla persona , non volontariamente causato dall\u2019interessato , n\u00e9 altrimenti evitabile , ferma restando la proporzionalit\u00e0 del fatto al pericolo .<\/p>\n<p>Chi con la 194 vorrebbe abolire questa ipotesi , non conosce il diritto .<\/p>\n<p>Le altre disposizioni della 194 che salvo nel quesito sono quelle sanzionatorie , con riferimento ai casi di interruzione colposa ( art. 17 ) , non volontaria per la donna ( art. 18 ) e volontaria per la stessa ( art. 19 ) della gravidanza .<\/p>\n<p>Quindi vengono confermate le norme sulla base delle quali gi\u00e0 oggi si punisce , sia pur con il riferimento a limitatissimi casi sugli aborti totali ( forse neppure l\u20191% ) , mentre con il successo referendario mediante la prevalenza dei \u201c S\u00ec \u201c su questo quesito la disciplina sanzionatoria riguarderebbe non meno del 99% dei casi di aborto , se si considera che le ipotesi in cui dalla gravidanza possa derivare il decesso della donna , anche considerati i progressi della medicina , sono veramente ridotte al minimo , come mi confermano gli stessi medici e ginecologi .<\/p>\n<p>Verrebbero in tal modo fatti salvi i due discutibili princ\u00ecpi affermati dalla consulta nella recente sentenza n. 13 del 2012 , con la quale sono stati rigettati i quesiti del referendum elettorale di matrice Dipietrista , che hanno sottolineato :<\/p>\n<p>a ) l\u2019inammissibilit\u00e0 di una reviviscenza di una legge ( abrogata , quali le incriminazioni del codice penale ) anteriore rispetto a quella oggetto di referendum ;<\/p>\n<p>b ) la necessit\u00e0 che , dall\u2019astratta abrogazione della legge , sia configurabile una normativa cosiddetta \u201c di risulta \u201c , quindi residua e tale da poter sopravvivere autonomamente ed essere immediatamente applicabile , regolando la materia .<\/p>\n<p>2 ) I quesiti minimali possibili ed efficaci per i nostri fini sostanziali sono molteplici .<\/p>\n<p>La formula che ho usato sin dall\u2019inizio \u00e8 volutamente non specifica , per evitare che qualche associazione usasse la virgola o il punto e virgola per giustificare la sua mancata adesione , mascherando , cos\u00ec , i propri interessi di marchio e di bottega , con implicazioni anche di carattere commerciale .<\/p>\n<p>Arrivati al punto in cui chiunque , anche alla luce dei miei appelli caduti nel nulla a formulare proposte concrete , pure il pi\u00f9 stolto tra coloro che si interessano alla questione , ha compreso che chi si dichiara antiabortista abrogazionista e non aderisce alla nostra iniziativa o \u00e8 un falso antiabortista abrogazionista o cerca di nobilitare con motivazioni tecniche ragioni di natura psicologica , ambizioni personali , se non direttamente interessi economici, ho deciso di rendere pubblico anche il secondo quesito .<\/p>\n<p>Quesito che , anche in questo caso , viene qui convertito per fini divulgativi in una forma che consenta una diretta lettura delle disposizioni di legge che rimarrebbero vigenti nei seguenti termini: <em>Volete che sia abrogata la legge 22 maggio 1978 n. 194 recante &#8220;Norme per la tutela sociale della maternit\u00e0 e sulla interruzione volontaria della gravidanza&#8221; , con riferimento agli artt. 1 , 2 , 3 , 4 , 5 , 7 comma 2 , 8 , 9 , 10 , 11 , 12 , 13 , 14 , 15 , 16 , 20 , 21 , 22 ad eccezione dell\u2019art. 6 , con riferimento alle parole \u201c L\u2019interruzione volontaria della gravidanza \u201c , \u201c pu\u00f2 essere praticata : a) quando la gravidanza o il parto comportino un grave pericolo per la vita della donna ; b) quando siano accertati processi patologici, tra cui quelli relativi a rilevanti anomalie o malformazioni del nascituro, che determinino un grave pericolo per la salute fisica o psichica della donna. \u201c , dell\u2019art. 7 commi 1 e 3 , che fissa le modalit\u00e0 di accertamento e limitazioni delle condizioni di cui al comma 6 , degli interi artt. 17 e 18 , che stabiliscono le pene per chiunque cagiona l\u2019interruzione di gravidanza senza il consenso della donna , dell\u2019art. 19 , con solo riferimento alle parole \u201cChiunque cagiona l&#8217;interruzione volontaria della gravidanza \u201c , \u201c\u00e8 punito con la reclusione sino a tre anni \u201c di cui al primo comma , alle parole \u201c La donna \u00e8 punita \u201c di cui al quarto comma , alle parole \u201cQuando l&#8217;interruzione volontaria della gravidanza avviene su donna minore degli anni diciotto, o interdetta,\u201c, \u201c chi la cagiona \u00e8 punito con \u201c , \u201c pene \u201c , \u201c aumentate fino alla met\u00e0 \u201c di cui al quinto comma e alle parole \u201cSe dai fatti previsti dai commi precedenti deriva la morte della donna, si applica la reclusione da tre a sette anni \u201c di cui al sesto comma ?<\/em><\/p>\n<p>Testo identico al massimale con la sola eccezione del riferimento ai casi di cui alla lettera b dell\u2019art. 6 , con cui comunque si estenderebbero ai primi 90 giorni di gravidanza le pi\u00f9 rigorose condizioni previste dal tale articolo , ed al primo e terzo comma dell\u2019art. 7 che si renderebbero necessari per l\u2019accertamento delle condizioni dell\u2019articolo precedente , con limiti nell\u2019ipotesi di vita autonoma del feto , che rende praticabile l\u2019aborto solo nel caso della lettera a ) .<\/p>\n<p>Quindi , non pi\u00f9 aborto libero , neppure nei primi 3 mesi di gestazione .<\/p>\n<p>Un testo , peraltro , proposto solo al fine di evitare che il nostro sforzo ( e posso parlare in prima persona nel definirlo quanto meno notevole , pur nella consapevolezza se nessuno mi ha obbligato ad affrontarlo ) cada nel nulla ( consentendoci di ottenere almeno un risultato parziale , significativo sul piano giuridico e culturale ) , a seguito dell\u2019eventuale censura della Consulta in ordine al citato contrasto del quesito massimale con l\u2019art. 32 della costituzione , che tutela il generale diritto alla salute , che sarebbe naturalmente considerato con riferimento alla potenziale madre e non al concepito .<\/p>\n<p>Una censura totalmente non condivisibile nel merito , perch\u00e9 l\u2019aborto non \u00e8 mai terapeutico , ma sempre possibile e quindi da non ignorare .<\/p>\n<p>Chiederemo , dunque , come da manifesto , l\u2019abrogazione totale e solo in subordine abrogazioni parziali , che , se accolte , rappresenterebbero comunque i presupposti sostanziali e culturali ( per una volta usiamo anche noi tale termine , spesso utilizzato con frequenza da chi intende nobilitare la propria inefficienza ) per il totale annientamento di una legge che sarebbe ad oggi precluso da ostacoli oggettivi frapposti dalle istituzioni ( come detto , dalla Corte Costituzionale ) .<\/p>\n<p>Altro sarebbe , ovviamente , limitare la propria azione volontariamente ed a seguito di un accordo con il potere politico-parlamentare ( che talvolta propone ai comitati referendari una modifica legislativa a parziale accoglimento dei quesiti dietro la rinuncia alla loro azione ) , che sarebbe frutto di una trattativa ignobilmente condotta sulla pelle del nostro prossimo .<\/p>\n<p>Un conto \u00e8 la scelta , un conto \u00e8 l\u2019imposizione dell\u2019autorit\u00e0 , da cui discende un oggettivo ostacolo .<\/p>\n<p>Non si pu\u00f2 ignorare o abrogare un\u2019irrevocabile decisione della Consulta , questa \u00e8 la realt\u00e0 nel nostro ordinamento .<\/p>\n<p>Chi dice o tutto o niente ( fermo restando che quel tutto deve costituire il nostro obiettivo ) a prescindere dalla realt\u00e0 , vive tra le nuvole e lass\u00f9 \u00e8 bene che continui a filosofare , operando nel mondo dei sogni , dove il senso pratico non esiste .<\/p>\n<p>Lo stesso mondo che frequentano coloro che si lamentano della vigenza di una legge ostentando i muscoli e digrignando i denti , senza fare nulla per abrogarla o senza aderire ad un\u2019iniziativa gi\u00e0 avviata in tal senso .<\/p>\n<p>3 ) Una terza ipotesi gi\u00e0 ventilata , quella di riproposizione tale e quale del quesito minimale gi\u00e0 ammesso nel 1981 ; deve essere valutata molto attentamente , giacch\u00e9 quel quesito , predisposto dal Movimento per la Vita nell\u2019\u00e0mbito di una pur lodevole operazione , presenta aspetti contrastanti con lo spirito della nostra iniziativa .<\/p>\n<p>Penso piuttosto ad un altro testo , che superi le censure pi\u00f9 rigorose della Corte costituzionale e sul quale sto lavorando .<\/p>\n<p>Un testo ulteriore che , lo ribadiamo , troverebbe la sua giustificazione sui vincoli formali imposti dalla Consulta e non su questioni ideali , essendo la nostra posizione chiaramente diretta a salvaguardare il diritto alla nascita del concepito , da affermare nel modo pi\u00f9 ampio possibile , con i soli limiti oggettivi imposti dal ordinamento giuridico del nostro paese che nessuno , tanto meno un avvocato , pu\u00f2 ignorare .<\/p>\n<p>Invito , come sempre , tutti coloro che ritengono che abbia un senso protestare contro qualcosa solo se si ha una proposta concreta diretta alla sua eliminazione e che comprendono che la piazza \u00e8 l\u2019unica via di protesta per un popolo solo in una dittatura ad aderire alla nostra iniziativa , finalizzata all\u2019utilizzo di uno strumento di democrazia diretta , tramite il sito ufficiale <a href=\"http:\/\/www.no194.org\/\">www.no194.org<\/a> .<\/p>\n<p>Ed invito tutti a partecipare alla \u201c 24ore per la vita \u201c ( da noi organizzata in collaborazione con un\u2019associazione nostra alleata , che ha aderito con tutti i suoi effettivi a NO194 ) che partir\u00e0 dalle ore 9 del 2-11-2012 e si svolger\u00e0 in corrispondenza delle chiese e degli ospedali indicati sul sito stesso , una manifestazione dalla matrice esplicitamente abrogazionista e nella quale sar\u00e0 meramente tollerata l\u2019eventuale presenza di parlamentari nazionali , in carica o meno .<\/p>\n<p>In tale prospettiva , si condanna sin d\u2019ora ogni ipotesi di strumentalizzazione dell\u2019evento da parte di costoro , responsabili in quanto tali per fatti o soprattutto , per ragioni anagrafiche , per omissioni della vigenza della normativa che vogliamo abrogare , alla luce dell\u2019assoluta assenza di iniziative esperite dagli stessi dirette a tal fine abrogativo .<\/p>\n<p align=\"center\">Pietro Guerini \u2013 Portavoce nazionale NO194<\/p>\n<p align=\"center\">\u00a0Pubblicato , tra gli altri , da <a href=\"http:\/\/www.pontifex.roma.it\/\">www.pontifex.roma.it<\/a> il 30-9-2012<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo aver trattato in passato la questione dei quesiti referendari , con tutte le sue implicazioni , anche pretestuose e strumentali , passiamo ora all\u2019analisi del loro testo , che viene per la prima volta qui reso pubblico . Una premessa doverosa . Il manifesto della nostra iniziativa referendaria , da me redatto e riportato [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[15],"class_list":["post-530","post","type-post","status-publish","format-standard","hentry","category-rassegna-stampa-specifica","tag-referendum"],"_links":{"self":[{"href":"https:\/\/www.no194.it\/wordpress\/wp-json\/wp\/v2\/posts\/530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.no194.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.no194.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.no194.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.no194.it\/wordpress\/wp-json\/wp\/v2\/comments?post=530"}],"version-history":[{"count":1,"href":"https:\/\/www.no194.it\/wordpress\/wp-json\/wp\/v2\/posts\/530\/revisions"}],"predecessor-version":[{"id":1083,"href":"https:\/\/www.no194.it\/wordpress\/wp-json\/wp\/v2\/posts\/530\/revisions\/1083"}],"wp:attachment":[{"href":"https:\/\/www.no194.it\/wordpress\/wp-json\/wp\/v2\/media?parent=530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.no194.it\/wordpress\/wp-json\/wp\/v2\/categories?post=530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.no194.it\/wordpress\/wp-json\/wp\/v2\/tags?post=530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}